{"id":17029,"date":"2019-08-20T09:34:39","date_gmt":"2019-08-20T07:34:39","guid":{"rendered":"https:\/\/www.tiendamuseodealtamira.com\/comprar\/bordeaux-tree-leaf-pendant\/"},"modified":"2019-08-20T09:34:43","modified_gmt":"2019-08-20T07:34:43","slug":"bordeaux-tree-leaf-pendant","status":"publish","type":"product","link":"https:\/\/www.tiendamuseodealtamira.com\/en\/purchase\/bordeaux-tree-leaf-pendant\/","title":{"rendered":"BORDEAUX TREE LEAF PENDANT"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Leaf-shaped pendant  inspired by the Altamira cave colors<\/p>\n","protected":false},"featured_media":16327,"template":"","meta":{"inline_featured_image":false,"_exactmetrics_skip_tracking":false},"product_brand":[],"product_cat":[307,310],"product_tag":[],"class_list":{"0":"post-17029","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-jewelry","7":"product_cat-necklaces","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/www.tiendamuseodealtamira.com\/en\/wp-json\/wp\/v2\/product\/17029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tiendamuseodealtamira.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.tiendamuseodealtamira.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tiendamuseodealtamira.com\/en\/wp-json\/wp\/v2\/media\/16327"}],"wp:attachment":[{"href":"https:\/\/www.tiendamuseodealtamira.com\/en\/wp-json\/wp\/v2\/media?parent=17029"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.tiendamuseodealtamira.com\/en\/wp-json\/wp\/v2\/product_brand?post=17029"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.tiendamuseodealtamira.com\/en\/wp-json\/wp\/v2\/product_cat?post=17029"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.tiendamuseodealtamira.com\/en\/wp-json\/wp\/v2\/product_tag?post=17029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}